{"id":7865,"date":"2023-11-20T16:34:30","date_gmt":"2023-11-20T15:34:30","guid":{"rendered":"https:\/\/aammb.cat\/?p=7865"},"modified":"2023-11-20T17:49:59","modified_gmt":"2023-11-20T16:49:59","slug":"exposicion-en-el-mmb-animales-a-bordo","status":"publish","type":"post","link":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/","title":{"rendered":"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!!"},"content":{"rendered":"<p><strong>Del 27 de Octubre de 2023 hasta el 3 de Marzo de 2024<\/strong><\/p>\n<p>Los animales y las personas han navegado en los mismos barcos durante muchos siglos. Las bestias se han embarcado hacia nuevos destinos porque la vida de la gente ha dependido absolutamente de ellos: para el cultivo, el transporte, la guerra, el consumo,&#8230; Y han compartido embarcaci\u00f3n \u2014y espacios\u2014 hasta que, a partir de de los a\u00f1os setenta, las legislaciones sobre su transporte se hicieron m\u00e1s estrictas.<\/p>\n<p>Por un lado, se cargaba ganado vivo para ir consumi\u00e9ndolo a lo largo de la traves\u00eda: gallos y gallinas, cerdos, corderos,&#8230; Por otro, hab\u00eda animales, como gatos o perros, que ten\u00edan trabajos asignados. Tambi\u00e9n hab\u00eda otros que se colaban, hecho que ocasionaba la desesperaci\u00f3n de la tripulaci\u00f3n: ratas, chinches, cucarachas y todo tipo de especies que, en barco, han ido invadiendo nuevos territorios. Y, por supuesto, siempre se han embarcado animales de compa\u00f1\u00eda.<\/p>\n<p>La exposici\u00f3n surge a ra\u00edz de las an\u00e9cdotas que se explican en una tertulia que el Museo celebra peri\u00f3dicamente con capitanes ya retirados de la marina mercante. La muestra se ilustra con fotograf\u00edas cedidas por colecciones p\u00fablicas y privadas, y se ha completado con fotograf\u00edas de mascotas a bordo de embarcaciones, conseguidas mediante un llamamiento en las redes sociales. Asimismo, presenta elementos l\u00fadicos como un photocall y juegos vinculados al relato del arca de No\u00e9.<\/p>\n<p>Desde el museo se ofrecer\u00e1n visitas comentadas exclusivas para socios y socias de la Asociaci\u00f3n de Amigos del Museo Mar\u00edtimo de Barcelona. \u00a1Cons\u00faltenos las fechas!<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>INFORMACI\u00d3N:<\/strong><\/span><br \/>\nFecha: Del 27\/10\/2023 al 03\/03\/2024<br \/>\nHorario: De 10:00h a 20:00h<br \/>\nLugar: Vest\u00edbulo del Museo Mar\u00edtimo de Barcelona<br \/>\nAcceso gratuito<\/p>\n<p>M\u00e1s info: <a href=\"https:\/\/www.mmb.cat\/es\/exposiciones\/animales-a-bordo\/\" target=\"_blank\" rel=\"noopener\"><strong>mmb.cat<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.mmb.cat\/es\/exposiciones\/animales-a-bordo\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7868\" src=\"http:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-MMB-Animals-a-Bord-AAMMB-amics-museu-maritim-barcelona.jpg\" alt=\"\" width=\"840\" height=\"425\" srcset=\"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-MMB-Animals-a-Bord-AAMMB-amics-museu-maritim-barcelona.jpg 840w, https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-MMB-Animals-a-Bord-AAMMB-amics-museu-maritim-barcelona-300x152.jpg 300w, https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-MMB-Animals-a-Bord-AAMMB-amics-museu-maritim-barcelona-768x389.jpg 768w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 27 de Octubre de 2023 hasta el 3 de Marzo de 2024 Los animales y las personas han navegado en los mismos barcos durante muchos siglos. Las bestias se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[139],"tags":[237,141,235,151,211],"class_list":["post-7865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exposiciones","tag-animales","tag-exposicion","tag-fotografia-es","tag-mmb-es","tag-museu-maritim-barcelona-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!! - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona<\/title>\n<meta name=\"description\" content=\"Exposici\u00f3n en el MMB Animales a bordo. Amics del Museu Mar\u00edtim de Barcelona AAMMB. Los animales y las personas han navegado en los mismos barcos durante muchos siglos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!! - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\" \/>\n<meta property=\"og:description\" content=\"Exposici\u00f3n en el MMB Animales a bordo. Amics del Museu Mar\u00edtim de Barcelona AAMMB. Los animales y las personas han navegado en los mismos barcos durante muchos siglos.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/\" \/>\n<meta property=\"og:site_name\" content=\"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-20T15:34:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-20T16:49:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"707\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AAMMB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AAMMB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/\"},\"author\":{\"name\":\"AAMMB\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#\\\/schema\\\/person\\\/850b04af58ae7ded291642cbf9d8dafc\"},\"headline\":\"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!!\",\"datePublished\":\"2023-11-20T15:34:30+00:00\",\"dateModified\":\"2023-11-20T16:49:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/\"},\"wordCount\":306,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg\",\"keywords\":[\"animales\",\"exposici\u00f3n\",\"fotograf\u00eda\",\"mmb\",\"museu mar\u00edtim barcelona\"],\"articleSection\":[\"Exposiciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/\",\"url\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/\",\"name\":\"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!! - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg\",\"datePublished\":\"2023-11-20T15:34:30+00:00\",\"dateModified\":\"2023-11-20T16:49:59+00:00\",\"description\":\"Exposici\u00f3n en el MMB Animales a bordo. Amics del Museu Mar\u00edtim de Barcelona AAMMB. Los animales y las personas han navegado en los mismos barcos durante muchos siglos.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg\",\"contentUrl\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg\",\"width\":707,\"height\":502},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-animales-a-bordo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/aammb.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#website\",\"url\":\"http:\\\/\\\/aammb.cat\\\/\",\"name\":\"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\",\"description\":\"Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\",\"publisher\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/#organization\"},\"alternateName\":\"AAMMB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/aammb.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#organization\",\"name\":\"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\",\"alternateName\":\"AAMMB\",\"url\":\"http:\\\/\\\/aammb.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-AAMMB-2.png\",\"contentUrl\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-AAMMB-2.png\",\"width\":320,\"height\":320,\"caption\":\"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\"},\"image\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/amics.museu\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@aammb\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#\\\/schema\\\/person\\\/850b04af58ae7ded291642cbf9d8dafc\",\"name\":\"AAMMB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g\",\"caption\":\"AAMMB\"},\"sameAs\":[\"http:\\\/\\\/aammb.cat\"],\"url\":\"https:\\\/\\\/aammb.cat\\\/es\\\/author\\\/adminaammb-cat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!! - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","description":"Exposici\u00f3n en el MMB Animales a bordo. Amics del Museu Mar\u00edtim de Barcelona AAMMB. Los animales y las personas han navegado en los mismos barcos durante muchos siglos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/","og_locale":"es_ES","og_type":"article","og_title":"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!! - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","og_description":"Exposici\u00f3n en el MMB Animales a bordo. Amics del Museu Mar\u00edtim de Barcelona AAMMB. Los animales y las personas han navegado en los mismos barcos durante muchos siglos.","og_url":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/","og_site_name":"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","article_published_time":"2023-11-20T15:34:30+00:00","article_modified_time":"2023-11-20T16:49:59+00:00","og_image":[{"width":707,"height":502,"url":"http:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg","type":"image\/jpeg"}],"author":"AAMMB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AAMMB","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/#article","isPartOf":{"@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/"},"author":{"name":"AAMMB","@id":"http:\/\/aammb.cat\/#\/schema\/person\/850b04af58ae7ded291642cbf9d8dafc"},"headline":"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!!","datePublished":"2023-11-20T15:34:30+00:00","dateModified":"2023-11-20T16:49:59+00:00","mainEntityOfPage":{"@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/"},"wordCount":306,"commentCount":0,"publisher":{"@id":"http:\/\/aammb.cat\/#organization"},"image":{"@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/#primaryimage"},"thumbnailUrl":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg","keywords":["animales","exposici\u00f3n","fotograf\u00eda","mmb","museu mar\u00edtim barcelona"],"articleSection":["Exposiciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/","url":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/","name":"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!! - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","isPartOf":{"@id":"http:\/\/aammb.cat\/#website"},"primaryImageOfPage":{"@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/#primaryimage"},"image":{"@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/#primaryimage"},"thumbnailUrl":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg","datePublished":"2023-11-20T15:34:30+00:00","dateModified":"2023-11-20T16:49:59+00:00","description":"Exposici\u00f3n en el MMB Animales a bordo. Amics del Museu Mar\u00edtim de Barcelona AAMMB. Los animales y las personas han navegado en los mismos barcos durante muchos siglos.","breadcrumb":{"@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/#primaryimage","url":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg","contentUrl":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicio-Animals-a-Bord-Animales-a-Bordo-MMB-AAMMB-amics-museu-maritim-barcelona.jpg","width":707,"height":502},{"@type":"BreadcrumbList","@id":"http:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-animales-a-bordo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/aammb.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Exposici\u00f3n en el MMB: \u00a1\u00a1Animales a bordo!!"}]},{"@type":"WebSite","@id":"http:\/\/aammb.cat\/#website","url":"http:\/\/aammb.cat\/","name":"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","description":"Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","publisher":{"@id":"http:\/\/aammb.cat\/#organization"},"alternateName":"AAMMB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/aammb.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/aammb.cat\/#organization","name":"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","alternateName":"AAMMB","url":"http:\/\/aammb.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/aammb.cat\/#\/schema\/logo\/image\/","url":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/03\/logo-AAMMB-2.png","contentUrl":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/03\/logo-AAMMB-2.png","width":320,"height":320,"caption":"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona"},"image":{"@id":"http:\/\/aammb.cat\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/amics.museu\/","https:\/\/www.youtube.com\/@aammb"]},{"@type":"Person","@id":"http:\/\/aammb.cat\/#\/schema\/person\/850b04af58ae7ded291642cbf9d8dafc","name":"AAMMB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g","caption":"AAMMB"},"sameAs":["http:\/\/aammb.cat"],"url":"https:\/\/aammb.cat\/es\/author\/adminaammb-cat\/"}]}},"_links":{"self":[{"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/posts\/7865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/comments?post=7865"}],"version-history":[{"count":5,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/posts\/7865\/revisions"}],"predecessor-version":[{"id":7911,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/posts\/7865\/revisions\/7911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/media\/7886"}],"wp:attachment":[{"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/media?parent=7865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/categories?post=7865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/tags?post=7865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}