{"id":7798,"date":"2023-11-10T14:06:18","date_gmt":"2023-11-10T13:06:18","guid":{"rendered":"https:\/\/aammb.cat\/?p=7798"},"modified":"2023-11-20T17:20:27","modified_gmt":"2023-11-20T16:20:27","slug":"exposicion-en-el-mmb-retratos-de-barcos","status":"publish","type":"post","link":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/","title":{"rendered":"Exposici\u00f3n en el MMB: Retratos de Barcos"},"content":{"rendered":"<p><strong>Retratos de barcos. Del siglo XIX a los \u00abshipspotters\u00bb<\/strong><\/p>\n<p><strong>Del 9 de Junio de 2023 hasta el 17 de Noviembre de 2024<\/strong><\/p>\n<p>Desde la antig\u00fcedad se han hecho representaciones gr\u00e1ficas de barcos pero rara vez se puede identificar el barco, es decir, conocer su nombre y su historia.<\/p>\n<p>Con esta exposici\u00f3n, el Museu Mar\u00edtim muestra c\u00f3mo han evolucionado los retratos de los barcos de la mano de los avances tecnol\u00f3gicos y de los cambios sociales, adapt\u00e1ndose a las herramientas de representaci\u00f3n de im\u00e1genes de cada momento, cambiando los motivos para hacer el retrato, de qui\u00e9n hace el encargo, as\u00ed como, los perfiles de los autores y la forma de difundirlos.<\/p>\n<p>La exposici\u00f3n se inicia con una breve introducci\u00f3n mostrando algunos antecedentes del s. XVIII. A partir de aqu\u00ed, se hace un recorrido cronol\u00f3gico mostrando c\u00f3mo ha ido cambiando la forma de realizar estos retratos y las t\u00e9cnicas que se han utilizado. Desde el siglo XIX, con el crecimiento de las grandes empresas navieras y el inicio de una gran demanda y producci\u00f3n de retratos pintados de barcos, hasta la actualidad con los <em>shipspotters<\/em> o observadores de barcos presentes en los puertos de todo el mundo que, adem\u00e1s de im\u00e1genes, comparten la informaci\u00f3n t\u00e9cnica de las embarcaciones.<\/p>\n<p>Desde el museo se ofrecer\u00e1n visitas comentadas exclusivas para socios y socias de la Asociaci\u00f3n de Amigos del Museo Mar\u00edtimo de Barcelona, de la mano de Teresa Sala, comisaria de la exposici\u00f3n y restauradora del museo. \u00a1Cons\u00faltenos las fechas!<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>INFORMACI\u00d3N:<\/strong><\/span><br \/>\nFechas: Del 09\/06\/2023 al 17\/11\/2024<br \/>\nHorario: De 10:00h a 20:00h<br \/>\nLugar: Naves de las Drassanes (nave 1)<\/p>\n<p>M\u00e1s info: <a href=\"https:\/\/www.mmb.cat\/es\/exposiciones\/retratos-de-barcos\/\" target=\"_blank\" rel=\"noopener\"><strong>mmb.cat<\/strong><\/a><br \/>\nTambi\u00e9n puede visitar la <strong><a href=\"https:\/\/my.mpskin.com\/ca\/tour\/zyd566913f\" target=\"_blank\" rel=\"noopener\">Exposici\u00f3n virtual en 3D haciendo click aqu\u00ed.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retratos de barcos. Del siglo XIX a los \u00abshipspotters\u00bb Del 9 de Junio de 2023 hasta el 17 de Noviembre de 2024 Desde la antig\u00fcedad se han hecho representaciones gr\u00e1ficas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[139],"tags":[234,141,151,211,180,233],"class_list":["post-7798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exposiciones","tag-barcos","tag-exposicion","tag-mmb-es","tag-museu-maritim-barcelona-es","tag-pintura-es","tag-retratos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exposici\u00f3n en el MMB: Retratos de Barcos - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona<\/title>\n<meta name=\"description\" content=\"Exposici\u00f3n en el MMB Retratos de Barcos Amics del Museu Mar\u00edtim de Barcelona AAMMB. Desde la antig\u00fcedad se han hecho representaciones gr\u00e1ficas de barcos pero rara vez se puede identificar el barco, es decir, conocer su nombre y su historia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposici\u00f3n en el MMB: Retratos de Barcos - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\" \/>\n<meta property=\"og:description\" content=\"Exposici\u00f3n en el MMB Retratos de Barcos Amics del Museu Mar\u00edtim de Barcelona AAMMB. Desde la antig\u00fcedad se han hecho representaciones gr\u00e1ficas de barcos pero rara vez se puede identificar el barco, es decir, conocer su nombre y su historia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/\" \/>\n<meta property=\"og:site_name\" content=\"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-10T13:06:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-20T16:20:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"707\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AAMMB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AAMMB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/\"},\"author\":{\"name\":\"AAMMB\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#\\\/schema\\\/person\\\/850b04af58ae7ded291642cbf9d8dafc\"},\"headline\":\"Exposici\u00f3n en el MMB: Retratos de Barcos\",\"datePublished\":\"2023-11-10T13:06:18+00:00\",\"dateModified\":\"2023-11-20T16:20:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/\"},\"wordCount\":308,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg\",\"keywords\":[\"barcos\",\"exposici\u00f3n\",\"mmb\",\"museu mar\u00edtim barcelona\",\"pintura\",\"retratos\"],\"articleSection\":[\"Exposiciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/\",\"url\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/\",\"name\":\"Exposici\u00f3n en el MMB: Retratos de Barcos - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg\",\"datePublished\":\"2023-11-10T13:06:18+00:00\",\"dateModified\":\"2023-11-20T16:20:27+00:00\",\"description\":\"Exposici\u00f3n en el MMB Retratos de Barcos Amics del Museu Mar\u00edtim de Barcelona AAMMB. Desde la antig\u00fcedad se han hecho representaciones gr\u00e1ficas de barcos pero rara vez se puede identificar el barco, es decir, conocer su nombre y su historia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg\",\"contentUrl\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg\",\"width\":707,\"height\":502},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aammb.cat\\\/es\\\/exposiciones\\\/exposicion-en-el-mmb-retratos-de-barcos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/aammb.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exposici\u00f3n en el MMB: Retratos de Barcos\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#website\",\"url\":\"http:\\\/\\\/aammb.cat\\\/\",\"name\":\"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\",\"description\":\"Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\",\"publisher\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/#organization\"},\"alternateName\":\"AAMMB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/aammb.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#organization\",\"name\":\"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\",\"alternateName\":\"AAMMB\",\"url\":\"http:\\\/\\\/aammb.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-AAMMB-2.png\",\"contentUrl\":\"https:\\\/\\\/aammb.cat\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-AAMMB-2.png\",\"width\":320,\"height\":320,\"caption\":\"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona\"},\"image\":{\"@id\":\"http:\\\/\\\/aammb.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/amics.museu\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@aammb\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/aammb.cat\\\/#\\\/schema\\\/person\\\/850b04af58ae7ded291642cbf9d8dafc\",\"name\":\"AAMMB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g\",\"caption\":\"AAMMB\"},\"sameAs\":[\"http:\\\/\\\/aammb.cat\"],\"url\":\"https:\\\/\\\/aammb.cat\\\/es\\\/author\\\/adminaammb-cat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposici\u00f3n en el MMB: Retratos de Barcos - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","description":"Exposici\u00f3n en el MMB Retratos de Barcos Amics del Museu Mar\u00edtim de Barcelona AAMMB. Desde la antig\u00fcedad se han hecho representaciones gr\u00e1ficas de barcos pero rara vez se puede identificar el barco, es decir, conocer su nombre y su historia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/","og_locale":"es_ES","og_type":"article","og_title":"Exposici\u00f3n en el MMB: Retratos de Barcos - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","og_description":"Exposici\u00f3n en el MMB Retratos de Barcos Amics del Museu Mar\u00edtim de Barcelona AAMMB. Desde la antig\u00fcedad se han hecho representaciones gr\u00e1ficas de barcos pero rara vez se puede identificar el barco, es decir, conocer su nombre y su historia.","og_url":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/","og_site_name":"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","article_published_time":"2023-11-10T13:06:18+00:00","article_modified_time":"2023-11-20T16:20:27+00:00","og_image":[{"width":707,"height":502,"url":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg","type":"image\/jpeg"}],"author":"AAMMB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AAMMB","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/#article","isPartOf":{"@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/"},"author":{"name":"AAMMB","@id":"http:\/\/aammb.cat\/#\/schema\/person\/850b04af58ae7ded291642cbf9d8dafc"},"headline":"Exposici\u00f3n en el MMB: Retratos de Barcos","datePublished":"2023-11-10T13:06:18+00:00","dateModified":"2023-11-20T16:20:27+00:00","mainEntityOfPage":{"@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/"},"wordCount":308,"commentCount":0,"publisher":{"@id":"http:\/\/aammb.cat\/#organization"},"image":{"@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/#primaryimage"},"thumbnailUrl":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg","keywords":["barcos","exposici\u00f3n","mmb","museu mar\u00edtim barcelona","pintura","retratos"],"articleSection":["Exposiciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/","url":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/","name":"Exposici\u00f3n en el MMB: Retratos de Barcos - aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","isPartOf":{"@id":"http:\/\/aammb.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/#primaryimage"},"image":{"@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/#primaryimage"},"thumbnailUrl":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg","datePublished":"2023-11-10T13:06:18+00:00","dateModified":"2023-11-20T16:20:27+00:00","description":"Exposici\u00f3n en el MMB Retratos de Barcos Amics del Museu Mar\u00edtim de Barcelona AAMMB. Desde la antig\u00fcedad se han hecho representaciones gr\u00e1ficas de barcos pero rara vez se puede identificar el barco, es decir, conocer su nombre y su historia.","breadcrumb":{"@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/#primaryimage","url":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg","contentUrl":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/11\/Exposicion-Exposicio-MMB-Retrats-de-Vaixells-Retratos-de-Barcos-aammb-amics-museu-maritim-barcelona.jpg","width":707,"height":502},{"@type":"BreadcrumbList","@id":"https:\/\/aammb.cat\/es\/exposiciones\/exposicion-en-el-mmb-retratos-de-barcos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/aammb.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Exposici\u00f3n en el MMB: Retratos de Barcos"}]},{"@type":"WebSite","@id":"http:\/\/aammb.cat\/#website","url":"http:\/\/aammb.cat\/","name":"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","description":"Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","publisher":{"@id":"http:\/\/aammb.cat\/#organization"},"alternateName":"AAMMB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/aammb.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/aammb.cat\/#organization","name":"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona","alternateName":"AAMMB","url":"http:\/\/aammb.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/aammb.cat\/#\/schema\/logo\/image\/","url":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/03\/logo-AAMMB-2.png","contentUrl":"https:\/\/aammb.cat\/wp-content\/uploads\/2023\/03\/logo-AAMMB-2.png","width":320,"height":320,"caption":"aammb - Associaci\u00f3 d&#039;Amics del Museu Mar\u00edtim de Barcelona"},"image":{"@id":"http:\/\/aammb.cat\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/amics.museu\/","https:\/\/www.youtube.com\/@aammb"]},{"@type":"Person","@id":"http:\/\/aammb.cat\/#\/schema\/person\/850b04af58ae7ded291642cbf9d8dafc","name":"AAMMB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e96758ad8a53b3678db7190af9de54ad58345ae0ba437a7ad41b67aa9256429?s=96&d=mm&r=g","caption":"AAMMB"},"sameAs":["http:\/\/aammb.cat"],"url":"https:\/\/aammb.cat\/es\/author\/adminaammb-cat\/"}]}},"_links":{"self":[{"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/posts\/7798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/comments?post=7798"}],"version-history":[{"count":5,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/posts\/7798\/revisions"}],"predecessor-version":[{"id":7909,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/posts\/7798\/revisions\/7909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/media\/7899"}],"wp:attachment":[{"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/media?parent=7798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/categories?post=7798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aammb.cat\/es\/wp-json\/wp\/v2\/tags?post=7798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}